{"id":2002,"date":"2026-08-22T09:59:03","date_gmt":"2026-08-22T07:59:03","guid":{"rendered":"https:\/\/www.zooalmaglio.ch\/?post_type=tribe_events&#038;p=2002"},"modified":"2026-08-22T10:04:33","modified_gmt":"2026-08-22T08:04:33","slug":"animal-experience-les-ratons-laveurs-4","status":"publish","type":"tribe_events","link":"https:\/\/www.zooalmaglio.ch\/fr\/event\/animal-experience-les-ratons-laveurs-4\/","title":{"rendered":"Animal Talk &#038; Experience &#8211; Les ratons laveurs"},"content":{"rendered":"<p><a href=\"https:\/\/www.zooalmaglio.ch\/fr\/achetez-vos-billets\/\">Acqu\u00e9rez de l&rsquo;exp\u00e9rience<\/a><\/p>\n","protected":false},"excerpt":{"rendered":"<p>Acqu\u00e9rez de l&rsquo;exp\u00e9rience<\/p>\n","protected":false},"author":2,"featured_media":0,"template":"","meta":{"_EventAllDay":false,"_EventTimezone":"Europe\/Zurich","_EventStartDate":"2026-09-05 16:00:00","_EventEndDate":"2026-09-05 16:00:00","_EventStartDateUTC":"2026-09-05 14:00:00","_EventEndDateUTC":"2026-09-05 14:00:00","_EventShowMap":true,"_EventShowMapLink":true,"_EventURL":"","_EventCost":"","_EventCostDescription":"","_EventCurrencySymbol":"$","_EventCurrencyCode":"","_EventCurrencyPosition":"","_EventDateTimeSeparator":"","_EventTimeRangeSeparator":"","_EventOrganizerID":[],"_EventVenueID":[],"_OrganizerEmail":"","_OrganizerPhone":"","_OrganizerWebsite":"","_VenueAddress":"","_VenueCity":"","_VenueCountry":"","_VenueProvince":"","_VenueState":"","_VenueZip":"","_VenuePhone":"","_VenueURL":"","_VenueStateProvince":"","_VenueLat":"","_VenueLng":"","_VenueShowMap":false,"_VenueShowMapLink":false,"_tribe_events_status":"","_tribe_events_status_reason":"","footnotes":""},"tags":[],"tribe_events_cat":[61],"class_list":["post-2002","tribe_events","type-tribe_events","status-publish","hentry","tribe_events_cat-animal-talk-experience","cat_animal-talk-experience"],"_links":{"self":[{"href":"https:\/\/www.zooalmaglio.ch\/fr\/wp-json\/wp\/v2\/tribe_events\/2002","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/www.zooalmaglio.ch\/fr\/wp-json\/wp\/v2\/tribe_events"}],"about":[{"href":"https:\/\/www.zooalmaglio.ch\/fr\/wp-json\/wp\/v2\/types\/tribe_events"}],"author":[{"embeddable":true,"href":"https:\/\/www.zooalmaglio.ch\/fr\/wp-json\/wp\/v2\/users\/2"}],"version-history":[{"count":3,"href":"https:\/\/www.zooalmaglio.ch\/fr\/wp-json\/wp\/v2\/tribe_events\/2002\/revisions"}],"predecessor-version":[{"id":2035,"href":"https:\/\/www.zooalmaglio.ch\/fr\/wp-json\/wp\/v2\/tribe_events\/2002\/revisions\/2035"}],"wp:attachment":[{"href":"https:\/\/www.zooalmaglio.ch\/fr\/wp-json\/wp\/v2\/media?parent=2002"}],"wp:term":[{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/www.zooalmaglio.ch\/fr\/wp-json\/wp\/v2\/tags?post=2002"},{"taxonomy":"tribe_events_cat","embeddable":true,"href":"https:\/\/www.zooalmaglio.ch\/fr\/wp-json\/wp\/v2\/tribe_events_cat?post=2002"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}