{"id":2384,"date":"2026-08-22T11:57:39","date_gmt":"2026-08-22T09:57:39","guid":{"rendered":"https:\/\/www.zooalmaglio.ch\/?post_type=tribe_events&#038;p=2384"},"modified":"2026-08-22T11:57:54","modified_gmt":"2026-08-22T09:57:54","slug":"animal-talk-experience-les-lions-7","status":"publish","type":"tribe_events","link":"https:\/\/www.zooalmaglio.ch\/fr\/event\/animal-talk-experience-les-lions-7\/","title":{"rendered":"Animal Talk &#038; Experience &#8211; Les lions"},"content":{"rendered":"<p><a href=\"https:\/\/www.zooalmaglio.ch\/fr\/achetez-vos-billets\/\">Acqu\u00e9rez de l&rsquo;exp\u00e9rience<\/a><\/p>\n","protected":false},"excerpt":{"rendered":"<p>Acqu\u00e9rez de l&rsquo;exp\u00e9rience<\/p>\n","protected":false},"author":2,"featured_media":0,"template":"","meta":{"_EventAllDay":false,"_EventTimezone":"Europe\/Zurich","_EventStartDate":"2026-09-13 17:00:00","_EventEndDate":"2026-09-13 17:00:00","_EventStartDateUTC":"2026-09-13 15:00:00","_EventEndDateUTC":"2026-09-13 15:00:00","_EventShowMap":true,"_EventShowMapLink":true,"_EventURL":"","_EventCost":"","_EventCostDescription":"","_EventCurrencySymbol":"$","_EventCurrencyCode":"","_EventCurrencyPosition":"","_EventDateTimeSeparator":"","_EventTimeRangeSeparator":"","_EventOrganizerID":[],"_EventVenueID":[],"_OrganizerEmail":"","_OrganizerPhone":"","_OrganizerWebsite":"","_VenueAddress":"","_VenueCity":"","_VenueCountry":"","_VenueProvince":"","_VenueState":"","_VenueZip":"","_VenuePhone":"","_VenueURL":"","_VenueStateProvince":"","_VenueLat":"","_VenueLng":"","_VenueShowMap":false,"_VenueShowMapLink":false,"_tribe_events_status":"","_tribe_events_status_reason":"","footnotes":""},"tags":[],"tribe_events_cat":[61],"class_list":["post-2384","tribe_events","type-tribe_events","status-publish","hentry","tribe_events_cat-animal-talk-experience","cat_animal-talk-experience"],"_links":{"self":[{"href":"https:\/\/www.zooalmaglio.ch\/fr\/wp-json\/wp\/v2\/tribe_events\/2384","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/www.zooalmaglio.ch\/fr\/wp-json\/wp\/v2\/tribe_events"}],"about":[{"href":"https:\/\/www.zooalmaglio.ch\/fr\/wp-json\/wp\/v2\/types\/tribe_events"}],"author":[{"embeddable":true,"href":"https:\/\/www.zooalmaglio.ch\/fr\/wp-json\/wp\/v2\/users\/2"}],"version-history":[{"count":2,"href":"https:\/\/www.zooalmaglio.ch\/fr\/wp-json\/wp\/v2\/tribe_events\/2384\/revisions"}],"predecessor-version":[{"id":2398,"href":"https:\/\/www.zooalmaglio.ch\/fr\/wp-json\/wp\/v2\/tribe_events\/2384\/revisions\/2398"}],"wp:attachment":[{"href":"https:\/\/www.zooalmaglio.ch\/fr\/wp-json\/wp\/v2\/media?parent=2384"}],"wp:term":[{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/www.zooalmaglio.ch\/fr\/wp-json\/wp\/v2\/tags?post=2384"},{"taxonomy":"tribe_events_cat","embeddable":true,"href":"https:\/\/www.zooalmaglio.ch\/fr\/wp-json\/wp\/v2\/tribe_events_cat?post=2384"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}