{"id":3305,"date":"2026-09-01T14:38:48","date_gmt":"2026-09-01T12:38:48","guid":{"rendered":"https:\/\/www.zooalmaglio.ch\/?post_type=tribe_events&#038;p=3305"},"modified":"2026-09-01T14:38:56","modified_gmt":"2026-09-01T12:38:56","slug":"spectacle-de-magie-au-zoo-3","status":"publish","type":"tribe_events","link":"https:\/\/www.zooalmaglio.ch\/fr\/event\/spectacle-de-magie-au-zoo-3\/","title":{"rendered":"Spectacle de magie au zoo"},"content":{"rendered":"<p>Pr\u00e9parez-vous \u00e0 vivre un spectacle plein de magie, d&rsquo;\u00e9merveillement et de divertissement pour toute la famille. Des illusions incroyables, des moments captivants et une journ\u00e9e inoubliable au c\u0153ur de la nature. <\/p>\n","protected":false},"excerpt":{"rendered":"<p>Pr\u00e9parez-vous \u00e0 vivre un spectacle plein de magie, d&rsquo;\u00e9merveillement et de divertissement pour toute la famille. Des illusions incroyables, des moments captivants et une journ\u00e9e inoubliable au c\u0153ur de la [&hellip;]<\/p>\n","protected":false},"author":2,"featured_media":638,"template":"","meta":{"_EventAllDay":false,"_EventTimezone":"Europe\/Zurich","_EventStartDate":"2026-09-20 10:00:00","_EventEndDate":"2026-09-20 13:30:00","_EventStartDateUTC":"2026-09-20 08:00:00","_EventEndDateUTC":"2026-09-20 11:30:00","_EventShowMap":false,"_EventShowMapLink":false,"_EventURL":"","_EventCost":"","_EventCostDescription":"","_EventCurrencySymbol":"$","_EventCurrencyCode":"","_EventCurrencyPosition":"","_EventDateTimeSeparator":"","_EventTimeRangeSeparator":"","_EventOrganizerID":[],"_EventVenueID":[],"_OrganizerEmail":"","_OrganizerPhone":"","_OrganizerWebsite":"","_VenueAddress":"","_VenueCity":"","_VenueCountry":"","_VenueProvince":"","_VenueState":"","_VenueZip":"","_VenuePhone":"","_VenueURL":"","_VenueStateProvince":"","_VenueLat":"","_VenueLng":"","_VenueShowMap":false,"_VenueShowMapLink":false,"_tribe_events_status":"","_tribe_events_status_reason":"","footnotes":""},"tags":[],"tribe_events_cat":[],"class_list":["post-3305","tribe_events","type-tribe_events","status-publish","has-post-thumbnail","hentry"],"_links":{"self":[{"href":"https:\/\/www.zooalmaglio.ch\/fr\/wp-json\/wp\/v2\/tribe_events\/3305","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/www.zooalmaglio.ch\/fr\/wp-json\/wp\/v2\/tribe_events"}],"about":[{"href":"https:\/\/www.zooalmaglio.ch\/fr\/wp-json\/wp\/v2\/types\/tribe_events"}],"author":[{"embeddable":true,"href":"https:\/\/www.zooalmaglio.ch\/fr\/wp-json\/wp\/v2\/users\/2"}],"version-history":[{"count":1,"href":"https:\/\/www.zooalmaglio.ch\/fr\/wp-json\/wp\/v2\/tribe_events\/3305\/revisions"}],"predecessor-version":[{"id":3308,"href":"https:\/\/www.zooalmaglio.ch\/fr\/wp-json\/wp\/v2\/tribe_events\/3305\/revisions\/3308"}],"wp:featuredmedia":[{"embeddable":true,"href":"https:\/\/www.zooalmaglio.ch\/fr\/wp-json\/wp\/v2\/media\/638"}],"wp:attachment":[{"href":"https:\/\/www.zooalmaglio.ch\/fr\/wp-json\/wp\/v2\/media?parent=3305"}],"wp:term":[{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/www.zooalmaglio.ch\/fr\/wp-json\/wp\/v2\/tags?post=3305"},{"taxonomy":"tribe_events_cat","embeddable":true,"href":"https:\/\/www.zooalmaglio.ch\/fr\/wp-json\/wp\/v2\/tribe_events_cat?post=3305"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}